{"id":7477,"date":"2024-03-06T22:14:19","date_gmt":"2024-03-06T21:14:19","guid":{"rendered":"https:\/\/www.dicea.unina.it\/?p=7477"},"modified":"2024-03-06T22:14:19","modified_gmt":"2024-03-06T21:14:19","slug":"7477-2","status":"publish","type":"post","link":"https:\/\/www.dicea.unina.it\/en\/7477-2\/","title":{"rendered":"Giornata Nazionale delle Universit\u00e0 &#8211; &#8220;Universit\u00e0 svelate&#8221; &#8211; 20 marzo 2024"},"content":{"rendered":"<p style=\"text-align: justify;\">L&#8217;<strong>University of Naples Federico II<\/strong> aderisce all&#8217;invito\u00a0della<strong> Conferenza dei Rettori delle Universit\u00e0 Italiane<\/strong> a partecipare alle celebrazioni della prima edizione della <strong>Giornata Nazionale delle Universit\u00e0 <\/strong><strong>&#8211; <\/strong><strong>\u201cUniversit\u00e0 svelate\u201d<\/strong><strong>, il 20 marzo 2024<\/strong><strong>.<\/strong><strong> Occasione per <\/strong>sensibilizzare la societ\u00e0 sul ruolo e sulla missione del sistema universitario nelle sue molteplici funzioni: ricerca, didattica, <em>public engagement<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>\u201cFederico II Svelata\u201d<\/strong> \u00e8 il contributo fridericiano a questa importante giornata di celebrazioni. Un programma ricco di iniziative, eventi, aree espositive e percorsi guidati, estesi a tutte le sedi dell\u2019Universit\u00e0, compresi i bellissimi complessi monumentali che le ospitano, che assume quest\u2019anno un significato particolare per la coincidenza con gli 800 anni dalla fondazione del pi\u00f9 antico Ateneo laico del mondo. La Federico II si aprir\u00e0 al pubblico per offrire una opportunit\u00e0 unica di partecipazione, un momento di condivisione del patrimonio scientifico e culturale e delle iniziative di valorizzazione della conoscenza che la comunit\u00e0 accademica produce per la societ\u00e0, con l\u2019obiettivo di mostrare dall\u2019interno la vita che si svolge nelle universit\u00e0, nelle aule, nei cortili, nelle biblioteche, nei musei e nei laboratori.<\/p>\n<p style=\"text-align: justify;\">La partecipazione agli eventi \u00e8 aperta a tutti gli interessati e gratuita. Collegandosi al sito <a href=\"http:\/\/www.f2svelata.it\/\">www.F2svelata.it<\/a> si pu\u00f2 consultare il programma dettagliato degli eventi e prenotarsi per la partecipazione.<\/p>\n<p style=\"text-align: justify;\">Per l\u2019occasione, \u00e8 stata disposta la sospensione delle attivit\u00e0 didattiche, fatte salve le sessioni di esami di profitto e di laurea.<\/p>\n<a href=\"https:\/\/www.dicea.unina.it\/wp-content\/uploads\/2024\/03\/Federico-Svelata.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"top\" data-toolbar-fixed=\"on\">Federico Svelata<\/a>","protected":false},"excerpt":{"rendered":"<p>L&#8217;Universit\u00e0 degli Studi di Napoli Federico II aderisce all&#8217;invito\u00a0della Conferenza dei Rettori delle Universit\u00e0 Italiane a partecipare alle celebrazioni della prima edizione della Giornata Nazionale delle Universit\u00e0 &#8211; \u201cUniversit\u00e0 svelate\u201d, il 20 marzo 2024. Occasione per sensibilizzare la societ\u00e0 sul ruolo e sulla missione del sistema universitario nelle sue molteplici funzioni: ricerca, didattica, public engagement.<\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-7477","post","type-post","status-publish","format-standard","hentry","category-events"],"nelio_content":{"isAutoShareEnabled":true,"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"followers":[1],"suggestedReferences":[],"efiUrl":"","efiAlt":"","highlights":[],"permalinkQueryArgs":[],"series":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Giornata Nazionale delle Universit\u00e0 - &quot;Universit\u00e0 svelate&quot; - 20 marzo 2024 - Dicea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dicea.unina.it\/en\/7477-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giornata Nazionale delle Universit\u00e0 - &quot;Universit\u00e0 svelate&quot; - 20 marzo 2024 - Dicea\" \/>\n<meta property=\"og:description\" content=\"L&#8217;Universit\u00e0 degli Studi di Napoli Federico II aderisce all&#8217;invito\u00a0della Conferenza dei Rettori delle Universit\u00e0 Italiane a partecipare alle celebrazioni della prima edizione della Giornata Nazionale delle Universit\u00e0 &#8211; \u201cUniversit\u00e0 svelate\u201d, il 20 marzo 2024. Occasione per sensibilizzare la societ\u00e0 sul ruolo e sulla missione del sistema universitario nelle sue molteplici funzioni: ricerca, didattica, public engagement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dicea.unina.it\/en\/7477-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicea\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-06T21:14:19+00:00\" \/>\n<meta name=\"author\" content=\"Dicea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dicea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dicea.unina.it\/7477-2\/\",\"url\":\"https:\/\/www.dicea.unina.it\/7477-2\/\",\"name\":\"Giornata Nazionale delle Universit\u00e0 - \\\"Universit\u00e0 svelate\\\" - 20 marzo 2024 - Dicea\",\"isPartOf\":{\"@id\":\"https:\/\/www.dicea.unina.it\/#website\"},\"datePublished\":\"2024-03-06T21:14:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.dicea.unina.it\/#\/schema\/person\/72dc54f8a9c1abf81e7f57ba4d733327\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.dicea.unina.it\/7477-2\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dicea.unina.it\/7477-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dicea.unina.it\/7477-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dicea.unina.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giornata Nazionale delle Universit\u00e0 &#8211; &#8220;Universit\u00e0 svelate&#8221; &#8211; 20 marzo 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dicea.unina.it\/#website\",\"url\":\"https:\/\/www.dicea.unina.it\/\",\"name\":\"Dicea\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dicea.unina.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dicea.unina.it\/#\/schema\/person\/72dc54f8a9c1abf81e7f57ba4d733327\",\"name\":\"Dicea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.dicea.unina.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6b8bac28f493ca95b624c69aa549bea1d9323b880751f41c3591c6149844693b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/6b8bac28f493ca95b624c69aa549bea1d9323b880751f41c3591c6149844693b?s=96&d=mm&r=g\",\"caption\":\"Dicea\"},\"sameAs\":[\"https:\/\/www.dicea.unina.it\"],\"url\":\"https:\/\/www.dicea.unina.it\/en\/author\/dicea\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giornata Nazionale delle Universit\u00e0 - \"Universit\u00e0 svelate\" - 20 marzo 2024 - Dicea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dicea.unina.it\/en\/7477-2\/","og_locale":"en_GB","og_type":"article","og_title":"Giornata Nazionale delle Universit\u00e0 - \"Universit\u00e0 svelate\" - 20 marzo 2024 - Dicea","og_description":"L&#8217;Universit\u00e0 degli Studi di Napoli Federico II aderisce all&#8217;invito\u00a0della Conferenza dei Rettori delle Universit\u00e0 Italiane a partecipare alle celebrazioni della prima edizione della Giornata Nazionale delle Universit\u00e0 &#8211; \u201cUniversit\u00e0 svelate\u201d, il 20 marzo 2024. Occasione per sensibilizzare la societ\u00e0 sul ruolo e sulla missione del sistema universitario nelle sue molteplici funzioni: ricerca, didattica, public engagement.","og_url":"https:\/\/www.dicea.unina.it\/en\/7477-2\/","og_site_name":"Dicea","article_published_time":"2024-03-06T21:14:19+00:00","author":"Dicea","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Dicea","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dicea.unina.it\/7477-2\/","url":"https:\/\/www.dicea.unina.it\/7477-2\/","name":"Giornata Nazionale delle Universit\u00e0 - \"Universit\u00e0 svelate\" - 20 marzo 2024 - Dicea","isPartOf":{"@id":"https:\/\/www.dicea.unina.it\/#website"},"datePublished":"2024-03-06T21:14:19+00:00","author":{"@id":"https:\/\/www.dicea.unina.it\/#\/schema\/person\/72dc54f8a9c1abf81e7f57ba4d733327"},"breadcrumb":{"@id":"https:\/\/www.dicea.unina.it\/7477-2\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dicea.unina.it\/7477-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dicea.unina.it\/7477-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dicea.unina.it\/"},{"@type":"ListItem","position":2,"name":"Giornata Nazionale delle Universit\u00e0 &#8211; &#8220;Universit\u00e0 svelate&#8221; &#8211; 20 marzo 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.dicea.unina.it\/#website","url":"https:\/\/www.dicea.unina.it\/","name":"Dicea","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dicea.unina.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/www.dicea.unina.it\/#\/schema\/person\/72dc54f8a9c1abf81e7f57ba4d733327","name":"Dicea","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.dicea.unina.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6b8bac28f493ca95b624c69aa549bea1d9323b880751f41c3591c6149844693b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b8bac28f493ca95b624c69aa549bea1d9323b880751f41c3591c6149844693b?s=96&d=mm&r=g","caption":"Dicea"},"sameAs":["https:\/\/www.dicea.unina.it"],"url":"https:\/\/www.dicea.unina.it\/en\/author\/dicea\/"}]}},"_links":{"self":[{"href":"https:\/\/www.dicea.unina.it\/en\/wp-json\/wp\/v2\/posts\/7477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dicea.unina.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dicea.unina.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dicea.unina.it\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dicea.unina.it\/en\/wp-json\/wp\/v2\/comments?post=7477"}],"version-history":[{"count":0,"href":"https:\/\/www.dicea.unina.it\/en\/wp-json\/wp\/v2\/posts\/7477\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dicea.unina.it\/en\/wp-json\/wp\/v2\/media?parent=7477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dicea.unina.it\/en\/wp-json\/wp\/v2\/categories?post=7477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dicea.unina.it\/en\/wp-json\/wp\/v2\/tags?post=7477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}